{"id":3041,"date":"2026-05-04T18:12:56","date_gmt":"2026-05-04T17:12:56","guid":{"rendered":"https:\/\/entrehuesosdecereza.com\/es\/?p=3041"},"modified":"2026-05-04T18:12:57","modified_gmt":"2026-05-04T17:12:57","slug":"espuma-de-fruta-congelada-en-thermomix","status":"publish","type":"post","link":"https:\/\/entrehuesosdecereza.com\/es\/espuma-de-fruta-congelada-en-thermomix\/","title":{"rendered":"Espuma de fruta congelada en Thermomix"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Ingredientes:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>100g de az\u00facar<\/li>\n\n\n\n<li>300g de fruta congelada en trozos ( Fresas, frutos rojos, melocot\u00f3n, ar\u00e1ndanos, frambuesas, tambi\u00e9n melocot\u00f3n en almibar, en este caso a\u00f1adir menos az\u00facar)<\/li>\n\n\n\n<li>2 cucharadas soperas de zumo de lim\u00f3n<\/li>\n\n\n\n<li>1 o 2 claras de huevo<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Elaboraci\u00f3n:<\/h2>\n\n\n\n<p>Poner el az\u00facar en el vaso<\/p>\n\n\n\n<p class=\"has-theme-palette-11-color has-text-color has-link-color has-medium-font-size wp-elements-2384908a65269a9817eef03c01bc85b4\">Pulverizar <strong>10seg Vel 10<\/strong><\/p>\n\n\n\n<p>A\u00f1adir la fruta y el zumo de lim\u00f3n<\/p>\n\n\n\n<p class=\"has-theme-palette-11-color has-text-color has-link-color has-medium-font-size wp-elements-fee14c6d7060da80cdfc22b6afb52725\">Triturar <strong>15seg Vel 5<\/strong> aumentando progresivamente a <strong>Vel 10<\/strong><\/p>\n\n\n\n<p>Bajar con la esp\u00e1tula y a\u00f1adir las claras de huevo<\/p>\n\n\n\n<p class=\"has-theme-palette-11-color has-text-color has-link-color has-medium-font-size wp-elements-e6719a19f9a891aacfc97e2a0de02197\"><strong>Mariposa 2min Vel 4<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Delicioso postre a base de fruta congelada batida con la Thermomix<\/p>\n","protected":false},"author":1,"featured_media":3042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[25,38,285],"tags":[325,326],"class_list":["post-3041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-postres","category-recetas-de-cocina","category-thermomix","tag-espuma","tag-fruta-congelada"],"_links":{"self":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/posts\/3041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/comments?post=3041"}],"version-history":[{"count":1,"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/posts\/3041\/revisions"}],"predecessor-version":[{"id":3043,"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/posts\/3041\/revisions\/3043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/media\/3042"}],"wp:attachment":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/media?parent=3041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/categories?post=3041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/tags?post=3041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}