{"id":3545,"date":"2026-05-07T18:47:10","date_gmt":"2026-05-07T17:47:10","guid":{"rendered":"https:\/\/entrehuesosdecereza.com\/es\/?p=3545"},"modified":"2026-05-07T18:47:11","modified_gmt":"2026-05-07T17:47:11","slug":"mezcla-de-especias-garam-masala-con-thermomix","status":"publish","type":"post","link":"https:\/\/entrehuesosdecereza.com\/es\/mezcla-de-especias-garam-masala-con-thermomix\/","title":{"rendered":"Mezcla de especias Garam Masala con Thermomix"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Ingredientes:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>2,5 cucharadas soperas de cardamomo molido<\/li>\n\n\n\n<li>1 cucharada sopera de pimienta negra en grano<\/li>\n\n\n\n<li>1 cucharada sopera de semillas de comino<\/li>\n\n\n\n<li>1 cucharada sopera de semillas de cilantro<\/li>\n\n\n\n<li>5 o 6 clavos<\/li>\n\n\n\n<li>1\/2 cucharaditas de nuez moscada molida<\/li>\n\n\n\n<li>2 cucharadas soperas de curry<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Elaboraci\u00f3n:<\/h2>\n\n\n\n<p>Tostar todos los ingredientes en el vaso<\/p>\n\n\n\n<p class=\"has-theme-palette-11-color has-text-color has-link-color has-medium-font-size wp-elements-073926b806cfde2119b8889a912a8d1c\"><strong>10min 120\u00baC Vel 0.5<\/strong><\/p>\n\n\n\n<p class=\"has-theme-palette-11-color has-text-color has-link-color has-medium-font-size wp-elements-2d05b297f053bfe00e9d8e7f14d34d9f\">Pulverizar <strong>40seg Vel 10<\/strong><\/p>\n\n\n\n<p class=\"has-large-font-size\">Sugerencias:<\/p>\n\n\n\n<p>Para adobos, salteados, sopas, galletas, ensaladas, etc<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingredientes: Elaboraci\u00f3n: Tostar todos los ingredientes en el vaso 10min 120\u00baC Vel 0.5 Pulverizar 40seg Vel 10 Sugerencias: Para adobos, salteados, sopas, galletas, ensaladas, etc<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[4,285],"tags":[107,461,333],"class_list":["post-3545","post","type-post","status-publish","format-standard","hentry","category-salados","category-thermomix","tag-especias","tag-garam-masala","tag-india"],"_links":{"self":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/posts\/3545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/comments?post=3545"}],"version-history":[{"count":1,"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/posts\/3545\/revisions"}],"predecessor-version":[{"id":3546,"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/posts\/3545\/revisions\/3546"}],"wp:attachment":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/media?parent=3545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/categories?post=3545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/tags?post=3545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}