{"id":117,"count":1,"description":"","link":"https:\/\/entrehuesosdecereza.com\/es\/tag\/espinacas\/","name":"espinacas","slug":"espinacas","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/tags\/117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/posts?tags=117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}