{"id":347,"count":1,"description":"","link":"https:\/\/entrehuesosdecereza.com\/es\/tag\/tamari\/","name":"tamari","slug":"tamari","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/tags\/347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/posts?tags=347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}