{"id":461,"count":1,"description":"","link":"https:\/\/entrehuesosdecereza.com\/es\/tag\/garam-masala\/","name":"garam masala","slug":"garam-masala","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/tags\/461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/entrehuesosdecereza.com\/es\/wp-json\/wp\/v2\/posts?tags=461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}